{"id":448,"date":"2021-02-05T22:18:29","date_gmt":"2021-02-05T22:18:29","guid":{"rendered":"https:\/\/blog.financialafrik.com\/?p=448"},"modified":"2021-03-29T22:00:52","modified_gmt":"2021-03-29T22:00:52","slug":"au-souvenir-de-kinshasa-sur-un-air-de-rumba","status":"publish","type":"post","link":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/","title":{"rendered":"Au souvenir de Kinshasa sur un air de Rumba"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>D&rsquo;apr\u00e8s les carnets de voyage du Prince Mandingue,  Balla Moussa Ke\u00efta<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Kinshasa, ville impersonnelle aux multiples facettes: s\u00e9duisante, troublante, et attachante. Mon s\u00e9jour pour la r\u00e9alisation de cet outil d\u2019int\u00e9gration,&nbsp; j&rsquo;ai nomm\u00e9 l\u2019Annuaire du commerce africain,&nbsp; n\u00e9 en cette ann\u00e9e 1991, ne fut pas de tout repos. Prospecter pendant cette p\u00e9riode sensible  o\u00f9 le destin de la nation Za\u00efroise se jouait au Palais du peuple, avec la conf\u00e9rence nationale,&nbsp; ponctu\u00e9e d\u2019\u00e9meutes, n\u2019\u00e9tait pas chose facile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette difficult\u00e9 due \u00e0 la situation socio-politique devenait, encore, un casse-t\u00eate quand la prospection devait se faire. Le  t\u00e9l\u00e9phone \u00e9tait d\u00e9faillant quand il existait.  &nbsp; La solution  \u00e9tait de faire le porte-\u00e0- porte \u00e0 notre corps d\u00e9fendant. Dans le meilleur des cas,  on trouvait sur place le directeur g\u00e9n\u00e9ral de l\u2019entreprise qui par l\u2019interm\u00e9diaire de sa secr\u00e9taire nous donnait un rendez-vous ferme. Donc, nous devons revenir sans \u00eatre s\u00fbr que cela sera honor\u00e9. Dans le pire des cas, nous multiplions les va et vient dans les entreprises sans jamais rencontrer le d\u00e9cideur et, &nbsp; \u00e0  plus forte raison,&nbsp; obtenir  un rendez-vous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A chaque r\u00e9veil,&nbsp; on se posait des questions&nbsp;:  y aurait-il \u00e9meutes, aurions-nous des rendez-vous, pourrions-nous circuler sans probl\u00e8me,&nbsp; le t\u00e9l\u00e9phone fonctionnera-t-il&nbsp;??? Autant de questions,&nbsp; auxquelles,&nbsp; nous n\u2019avions pas de r\u00e9ponses. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ne pouvant nous permettre de continuer dans cette voie, il fallait changer de strat\u00e9gie.&nbsp; C&rsquo;est ainsi qu\u2019une fois de plus,  nous sollicit\u00e2mes  L\u2019ANEZA (Agence Nationale des Entreprises du Za\u00efre), aujourd\u2019hui appel\u00e9e la FEC (F\u00e9d\u00e9ration des Entreprises du Congo ), afin de nous permettre pendant leurs diff\u00e9rentes r\u00e9unions hebdomadaires avec leurs membres d&rsquo;exposer le but de notre mission au Za\u00efre. Ce qui nous permettait de toucher sur place,&nbsp; au m\u00eame moment,&nbsp; un grand nombres de dirigeants d\u2019entreprises.&nbsp; Strat\u00e9gie qui fut&nbsp; plus ou moins salutaire\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de cette approche, j&rsquo;ai d\u00fb me rendre un matin \u00e0 la grande poste de Kinshasa sur le boulevard du 30 juin ( date de l\u2019ind\u00e9pendance en 1960 ), &nbsp;pour en savoir plus sur le t\u00e9l\u00e9phone.&nbsp; C\u2019est ainsi qu&rsquo;on me pr\u00e9sentera un op\u00e9rateur qui me fera la proposition suivante: lui donner la liste de mes prospects, le num\u00e9ro de mon h\u00f4tel et de ma chambre,&nbsp; afin qu&rsquo;il me passe mes coups de fils.&nbsp; Le parcours du combattant&nbsp;! J\u2019ai attendu des journ\u00e9es enti\u00e8res&nbsp; sans que je ne re\u00e7oive aucun coup de fil surtout quand il s\u2019agit de joindre Abidjan,&nbsp; ma base\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce temps fou que je passais dans ma chambre d\u2019h\u00f4tel,&nbsp; \u00e0 attendre l\u2019op\u00e9rateur de la grande poste, \u00e9tait orn\u00e9 au d\u00e9but de chaque journal parl\u00e9 de la Radio T\u00e9l\u00e9vision Za\u00efroise (RTZ)  par la voix de \u00ab\u00a0Tata Mukonzi\u00a0\u00bb,  le chef supr\u00eame,&nbsp; le Pr\u00e9sident Mobutu Sese Seko Kuku Gbendo wa zbanga, qui disait ceci&nbsp;: \u00ab\u00a0Na lingi Za\u00efre lisant moko, tata bo, mama bo, ekolobo\u2026\u00a0\u00bb et le peuple r\u00e9pondait \u00ab\u00a0Moko\u00a0\u00bb&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ce slogan en langue nationale (Lingala), le Pr\u00e9sident&nbsp; Mobutu disait dans un \u00e9lan nationaliste&nbsp;: \u00ab\u00a0Je souhaite que le Za\u00efre soit une seule nation, un seul peuple, un seul drapeau,&nbsp; \u00e9videmment un seul parti,\u00a0\u00bb,  le&nbsp; MPR (Mouvement Pour la R\u00e9volution)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du coup,  en \u00e9coutant \u00ab\u00a0Tata Mukonzi\u00a0\u00bb,  je pensais \u00e0 cette autre p\u00e9riode de ma vie, pendant les ann\u00e9es &nbsp;70 et 80 o\u00f9,&nbsp; \u00e9tudiant \u00e0 Lom\u00e9,&nbsp; je me rendais souvent \u00e0 Cotonou, au B\u00e9nin, o\u00f9 on arr\u00eatait la musique en pleine bo\u00eete de nuit pour passer le journal parl\u00e9 du pays, qui commen\u00e7ait par la voix du Pr\u00e9sident feu Mathieu K\u00e9r\u00e9kou&nbsp;: \u00ab\u00a0Ehuzu Dadan\u00a0\u00bb (Vive la r\u00e9volution)&nbsp;! En C\u00f4te d\u2019Ivoire,&nbsp; le journal parl\u00e9 commen\u00e7ait par la \u00ab\u00a0la pens\u00e9e du jour\u00a0\u00bb du Pr\u00e9sident F\u00e9lix Houphou\u00ebt-Boigny. En Guin\u00e9e,  le Pr\u00e9sident Ahmed  S\u00e9kou Tour\u00e9 criait \u00ab\u00a0vive la r\u00e9volution et le progr\u00e8s social\u00a0\u00bb, tout fustigeant l\u2019imp\u00e9rialisme,&nbsp; le capitalisme et le colonialisme\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oui, quelle nostalgie&nbsp;! C\u2019\u00e9tait l\u2019Afrique des \u00ab\u00a0p\u00e8res fondateurs\u00a0\u00bb,&nbsp; p\u00e8res de la nation.  Il y a  a des moments o\u00f9 nos \u00ab\u00a0d\u00e9mocrates actuels\u00a0\u00bb nous font regretter nos \u00ab\u00a0dictateurs d\u2019hier\u00a0\u00bb.  Autoritaires certes mais ils avaient une vision pour l\u2019Afrique,&nbsp; une certaine grandeur\u2026 il suffit de voir certaines de leurs r\u00e9alisations dans nos diff\u00e9rents  pays pour s&rsquo;en rendre compte. Des \u00e9difices qui r\u00e9sistent au temps et \u00e0 l&rsquo;espace\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kinshasa, la ville magique, ing\u00e9nieuse. &nbsp; o\u00f9 malgr\u00e9 la mis\u00e8re qu&rsquo;on peut d\u00e9tecter par ci ou par l\u00e0,&nbsp; comme partout sur notre continent,&nbsp; le congolais reste inventif, cr\u00e9atif avec \u00e0 la cl\u00e9, la joie de vivre&nbsp;! Kinshasa est reine de la d\u00e9brouillardise. La ville grouillait au rythme de la Rumba. La bi\u00e8re coulait \u00e0 flot  flot et les ambianceurs en  mettaient  plein la vue, les sapeurs  rivalisaient le long d&rsquo;interminables soir\u00e9es. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je connaissais assez bien cette ville pour l&rsquo;avoir d\u00e9couverte la premi\u00e8re fois en 1982&nbsp;; r\u00e9sident entre 1982-1986 \u00e0 Pointe-Noire au Congo Brazzaville, o\u00f9 il n&rsquo;y a ni repr\u00e9sentation &nbsp;diplomatique  ou consulaire ivoirienne,&nbsp; j\u2019\u00e9tais sens\u00e9 me rendre chaque fois \u00e0  Kinshasa qui abritait l\u2019ambassade de la C\u00f4te d\u2019Ivoire afin de r\u00e9gler tout probl\u00e8me d\u2019ordre administratif me concernant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette ville  me rappelait Abidjan, avec ses bus de la SOTRAZ peints en vert, comme de la SOTRA, avec ses buildings et art\u00e8res du centre ville. &nbsp; La  seule diff\u00e9rence \u00e9tait que Kinshasa la Belle \u00e9tait plus peupl\u00e9e. C\u2019est la ville o\u00f9 j&rsquo;ai vu pour la premi\u00e8re fois&nbsp; le contenu d&rsquo;un conteneur de bo\u00eete de sardines se vider en une journ\u00e9e.&nbsp; S&rsquo;il vous pla\u00eet, vendu en d\u00e9tail. Ce spectacle m&rsquo;a fait penser  \u00e0 King Sony Ad\u00e9, chanteur et musicien nigerian qui disait que la population nigeriane le suffisait pour qu&rsquo;il rentre dans ses fois une fois qu&rsquo;il mettait un disque sur le march\u00e9. Oui l\u00e0 &nbsp;o\u00f9 il y a foule ,le potentiel est pr\u00e9sent pour la consommation. La population peut \u00eatre un facteur de d\u00e9veloppement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je profitais de mes week-ends, apr\u00e8s une semaine harassante  \u00e0 \u00e9cumer les quartiers de Kinshasa ( Barumbu, Lingwala, Kimbaseke, Sinkin, Kintambo, Maluku\u2026.).  J&rsquo;aimais le faire souvent d\u00e9guis\u00e9,&nbsp; c\u2019est-\u00e0-dire en me mettant&nbsp; dans la peau de l&rsquo;autochtone&nbsp;: le cam\u00e9l\u00e9on. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il m\u2019arrivait de m&rsquo;attabler dans un bar o\u00f9 bruit de bouteilles de bi\u00e8re et  d\u00e9cibels font m\u00e9nage&nbsp;! Avec ma bouteille de coca- col\u00e0, mon d\u00e9guisement finissait toujours pour \u00eatre d\u00e9couvert, oui parce que j&rsquo;\u00e9tais le seul \u00e0 ne pas boire \u00ab\u00a0Tonton Skol\u00a0\u00bb, &nbsp;la bi\u00e8re locale,&nbsp; tr\u00e8s pris\u00e9e\u00e0  l\u2019\u00e9poque. Cette bi\u00e8re \u00e9tait c\u00e9l\u00e9br\u00e9e par les orchestres Swede Su\u00e8de, Zaiko langa langa pendant le festival Tonton &nbsp;skol. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est \u00e0 l\u2019occasion d&rsquo;une de mes escapades, dans le quartier Sinkin, \u00e0 un carrefour que je rendrais service \u00e0 une dame, en la laissant monter dans le taxi o\u00f9 j\u2019avais&nbsp; pris place. Elle partait \u00e0 Ngalima,  me dira t-elle. \u00c7a faisait une heure de temps qu\u2019elle&nbsp; attendait un taxi, tellement il est difficile la mobilit\u00e9 a Kin makambo\u2026 la dame, c\u2019\u00e9tait Marie Claire Mboyo dite Mbilia Bel&nbsp;!!!&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les nuits a Kinshasa sont meubl\u00e9es d&rsquo;arts et de culture, l\u2019ambiance est partout festive&nbsp;; que ce soit \u00e0 Kimpouenza  o\u00f9 Papa Wemba, l&rsquo;idole des jeunes,  chez Rochereau dit Tabuley, \u00e0  Mayaza, au Topo, sans oublier les bo\u00eetes de nuit \u00ab\u00a0New-jet,watergate\u00a0\u00bb&nbsp; o\u00f9 j&rsquo;ai rencontr\u00e9 les enfants Mobutu et fait la connaissance de Abeti Masikini. La boisson et la musique rivalisaient au bord du Congo\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J&rsquo;avoue que j\u2019avais la chance d\u2019\u00eatre souvent dans certains endroits o\u00f9, \u00e0 moins d&rsquo;\u00eatre des diplomates, &nbsp; on ne rencontrait pas d&rsquo;ouest africains.  Gr\u00e2ce aux 3 \u00ab&nbsp; oirs\u00a0\u00bb,  les relations humaines,&nbsp; aussi soit gr\u00e2ce \u00e0 mon nom, ou \u00e0 ma taille, je pouvais me permettre de me pointer dans des coins r\u00e9serv\u00e9s au jet-set\u2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec mon pr\u00e9nom Balla Moussa,&nbsp; j\u2019\u00e9tais souvent pris pour un Parent de Pierre Moussa, ministre influent au Congo Brazzaville\u2026 au lieu de Balla,&nbsp; on m&rsquo;appelait M&rsquo;Balla, pour certains j\u2019\u00e9tais congolais ou Camerounais, en un mot un bantou, sauf Za\u00efrois . Oui je ne pouvais pas \u00eatre za\u00efrois parce que je mettais des cravates, interdits durant  cette belle \u00e9poque de l\u2019authenticit\u00e9. Abascos ( abas costume&nbsp; ) faisait foi&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une autre \u00e9poque de l\u2019Afrique o\u00f9 le Za\u00efre \u00e9tait une r\u00e9f\u00e9rence&nbsp;: le combat Ali-Forman, en football\u2026 repr\u00e9senter  l\u2019Afrique \u00e0 la coupe du monde\u2026. Son Ministre, pardon son commissaire \u00e0 l\u2019information,  Sakombi Inongo, qui sillonnait  l\u2019Afrique pour expliquer ce que c&rsquo;est que l\u2019authenticit\u00e9&nbsp;? C\u2019est ainsi qu&rsquo;il a influenc\u00e9 le Togo, le pr\u00e9sident \u00c9tienne Eyadema, s\u2019appellera Gnassingbe\u2026 Au S\u00e9n\u00e9gal&nbsp; le Pr\u00e9sident Senghor lui r\u00e9pondra&nbsp;avec sa diction l\u00e9gendaire: \u00ab\u00a0l\u2019authenticit\u00e9 est une forme zairoise de la n\u00e9gritude\u00a0\u00bb&nbsp;dixit.  Nous \u00e9tions en pleine guerre froide, et l\u2019Afrique n&rsquo;y \u00e9chappait pas&nbsp;:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;iI y avait les pays non align\u00e9s &nbsp; et le bloc de l&rsquo;ouest. Il y avait les magazines Jeune Afrique,&nbsp; et Afrique Asie.  Aujourd\u2019hui, nous avons la COP 21  et la COVID-19&nbsp;! Qui l&#8217;emportera&nbsp;? Quand on voit aujourd\u2019hui comment&nbsp; ces grandes puissances se battent chacune de son c\u00f4t\u00e9 pour le climat  et la course aux &nbsp;vaccins, l&rsquo;on voit que les deux blocs sont encore l\u00e0.&nbsp; H\u00e9las avec l&rsquo;Afrique comme  parent pauvre, qui doit acheter deux \u00e0 trois fois plus cher\u2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;Le s\u00e9jour kinois est plus long que pr\u00e9vu, faute de la prospection qui avance cahin caha,&nbsp; mais avec&nbsp; de bonnes r\u00e9coltes tel ce contrat que je venais de signer avec la compagnie Air Za\u00a8re, fleuron et outil de la propagande r\u00e9volutionnaire de l&rsquo;homme au toque de l\u00e9opard,&nbsp; l&rsquo;\u00e9l\u00e9gant et imposant par sa voix et par sa carrure, Mobutu Sese Seko Kuku Gbendo wa zabanga, un leader que l&rsquo;Afrique enterra vite, en un bloc, sans faire l&rsquo;inventaire de son authenticit\u00e9, l&rsquo;examen de cet appel pressant \u00e0 revenir aux sources fondamentales de l&rsquo;Afrique, de sa culture mill\u00e9naire et de sa fa\u00e7on d&rsquo;\u00eatre et de s&rsquo;appeler. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0&nbsp; ce contrat sign\u00e9 avec M Molosa, responsable commercial, nous voici dans l\u2019avion pour Kigali. Ce vol est sp\u00e9cial car il est le vol inaugural de la compagnie Air Za\u00efre pour le Rwanda. Nous ne sommes que 5 passagers,&nbsp; dont le Directeur Commercial, &nbsp;M Zuchi. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Du ciel, j\u2019aper\u00e7ois le fleuve Congo, fronti\u00e8re naturelle entre le Za\u00efre ( RDC), le Congo Brazzaville,&nbsp; et l&rsquo;Angola. Avec ses 4700 km de longueur, il est le 8 \u00e8me fleuve le plus long du monde. Telle une force tranquille, coule, et coule\u2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce n&rsquo;est qu&rsquo;un au revoir, je reviendrais a Kin la belle, une ville inspirante et vivante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D&rsquo;apr\u00e8s les carnets de voyage du Prince Mandingue, Balla Moussa Ke\u00efta. Kinshasa, ville impersonnelle aux multiples facettes: s\u00e9duisante, troublante, et attachante. Mon s\u00e9jour pour la r\u00e9alisation de cet outil d\u2019int\u00e9gration,&nbsp; j&rsquo;ai nomm\u00e9 l\u2019Annuaire du commerce africain,&nbsp; n\u00e9 en cette ann\u00e9e 1991, ne fut pas de tout repos. Prospecter pendant cette p\u00e9riode sensible o\u00f9 le destin [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[99,9,1],"tags":[49,84,86],"class_list":["post-448","post","type-post","status-publish","format-standard","has-post-thumbnail","category-carnets-de-route","category-featured","category-uncategorized","tag-balla-moussa-keita","tag-felix-houphouet-boigny","tag-mobutu-sese-seko"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Touristic Afrik | Au souvenir de Kinshasa sur un air de Rumba<\/title>\n<meta name=\"description\" content=\"Les derni\u00e8res news sur l\u2019h\u00f4tellerie, les voyagistes et les compagnies a\u00e9riennes. Exp\u00e9rience client, avis et reportages. Touristic Afrik est un site sp\u00e9cialis\u00e9 du Groupe Financial Afrik.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Touristic Afrik | Au souvenir de Kinshasa sur un air de Rumba\" \/>\n<meta property=\"og:description\" content=\"Les derni\u00e8res news sur l\u2019h\u00f4tellerie, les voyagistes et les compagnies a\u00e9riennes. Exp\u00e9rience client, avis et reportages. Touristic Afrik est un site sp\u00e9cialis\u00e9 du Groupe Financial Afrik.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/\" \/>\n<meta property=\"og:site_name\" content=\"Touristic Afrik\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FinancialAfrik\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-05T22:18:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-29T22:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/financialafrik.com\/touristicafrik\/wp-content\/uploads\/2020\/06\/Balla-Moussa-Keita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Balla Moussa Keita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Financialafrik\" \/>\n<meta name=\"twitter:site\" content=\"@Financialafrik\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Balla Moussa Keita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/\"},\"author\":{\"name\":\"Balla Moussa Keita\",\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/#\\\/schema\\\/person\\\/ccf215c04eace169146fe681d585b837\"},\"headline\":\"Au souvenir de Kinshasa sur un air de Rumba\",\"datePublished\":\"2021-02-05T22:18:29+00:00\",\"dateModified\":\"2021-03-29T22:00:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/\"},\"wordCount\":1970,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Balla-Moussa-Keita.jpg\",\"keywords\":[\"Balla Moussa Keita\",\"F\u00e9lix Houphou\u00ebt-Boigny\",\"Mobutu Sese Seko\"],\"articleSection\":[\"Carnets de route\",\"Featured\",\"Uncategorized\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/\",\"url\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/\",\"name\":\"Touristic Afrik | Au souvenir de Kinshasa sur un air de Rumba\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Balla-Moussa-Keita.jpg\",\"datePublished\":\"2021-02-05T22:18:29+00:00\",\"dateModified\":\"2021-03-29T22:00:52+00:00\",\"description\":\"Les derni\u00e8res news sur l\u2019h\u00f4tellerie, les voyagistes et les compagnies a\u00e9riennes. Exp\u00e9rience client, avis et reportages. Touristic Afrik est un site sp\u00e9cialis\u00e9 du Groupe Financial Afrik.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Balla-Moussa-Keita.jpg\",\"contentUrl\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/Balla-Moussa-Keita.jpg\",\"width\":940,\"height\":1024,\"caption\":\"Balla Moussa Keita. (Photo Vincent Fournier).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/2021\\\/02\\\/05\\\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Au souvenir de Kinshasa sur un air de Rumba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/#website\",\"url\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/\",\"name\":\"Touristic Afrik\",\"description\":\"L\u2019actualit\u00e9 touristique africaine\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/#organization\",\"name\":\"Touristic Afrik\",\"url\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/touristicafrik.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/blog-FA_Plan-de-travail-1.png\",\"contentUrl\":\"https:\\\/\\\/touristicafrik.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/blog-FA_Plan-de-travail-1.png\",\"width\":1115,\"height\":242,\"caption\":\"Touristic Afrik\"},\"image\":{\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FinancialAfrik\\\/\",\"https:\\\/\\\/x.com\\\/Financialafrik\",\"https:\\\/\\\/www.instagram.com\\\/financial_afrik\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/pub\\\/financial-afrik\\\/71\\\/727\\\/4bb\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCSeoXcgLHLSVaKqMP7cQaJQ\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/#\\\/schema\\\/person\\\/ccf215c04eace169146fe681d585b837\",\"name\":\"Balla Moussa Keita\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dcb5af52f0a864e870758e648ac35d7815718bac8b99244bd3943efaca1f896?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dcb5af52f0a864e870758e648ac35d7815718bac8b99244bd3943efaca1f896?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4dcb5af52f0a864e870758e648ac35d7815718bac8b99244bd3943efaca1f896?s=96&d=mm&r=g\",\"caption\":\"Balla Moussa Keita\"},\"description\":\"30 ans de voyage dans 37 des 54 pays africains. Les chroniques de Balla Moussa Keita offrent une image nette de l'Afrique en mouvement, \u00e0 travers ses paysages, l'ambiance de ses villes mais aussi les rapports sociaux entre tribus et ethnies. De nationalit\u00e9 ivoirienne, Balla Moussa Keita a travaill\u00e9 dans de nombreux m\u00e9dias panafricains.\",\"url\":\"https:\\\/\\\/www.financialafrik.com\\\/touristicafrik\\\/author\\\/balla-moussa-keita\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Touristic Afrik | Au souvenir de Kinshasa sur un air de Rumba","description":"Les derni\u00e8res news sur l\u2019h\u00f4tellerie, les voyagistes et les compagnies a\u00e9riennes. Exp\u00e9rience client, avis et reportages. Touristic Afrik est un site sp\u00e9cialis\u00e9 du Groupe Financial Afrik.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/","og_locale":"fr_FR","og_type":"article","og_title":"Touristic Afrik | Au souvenir de Kinshasa sur un air de Rumba","og_description":"Les derni\u00e8res news sur l\u2019h\u00f4tellerie, les voyagistes et les compagnies a\u00e9riennes. Exp\u00e9rience client, avis et reportages. Touristic Afrik est un site sp\u00e9cialis\u00e9 du Groupe Financial Afrik.","og_url":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/","og_site_name":"Touristic Afrik","article_publisher":"https:\/\/www.facebook.com\/FinancialAfrik\/","article_published_time":"2021-02-05T22:18:29+00:00","article_modified_time":"2021-03-29T22:00:52+00:00","og_image":[{"width":940,"height":1024,"url":"financialafrik.com\/touristicafrik\/wp-content\/uploads\/2020\/06\/Balla-Moussa-Keita.jpg","type":"image\/jpeg"}],"author":"Balla Moussa Keita","twitter_card":"summary_large_image","twitter_creator":"@Financialafrik","twitter_site":"@Financialafrik","twitter_misc":{"\u00c9crit par":"Balla Moussa Keita","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/#article","isPartOf":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/"},"author":{"name":"Balla Moussa Keita","@id":"https:\/\/www.financialafrik.com\/touristicafrik\/#\/schema\/person\/ccf215c04eace169146fe681d585b837"},"headline":"Au souvenir de Kinshasa sur un air de Rumba","datePublished":"2021-02-05T22:18:29+00:00","dateModified":"2021-03-29T22:00:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/"},"wordCount":1970,"commentCount":0,"publisher":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/#organization"},"image":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-content\/uploads\/2020\/06\/Balla-Moussa-Keita.jpg","keywords":["Balla Moussa Keita","F\u00e9lix Houphou\u00ebt-Boigny","Mobutu Sese Seko"],"articleSection":["Carnets de route","Featured","Uncategorized"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/","url":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/","name":"Touristic Afrik | Au souvenir de Kinshasa sur un air de Rumba","isPartOf":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/#primaryimage"},"image":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-content\/uploads\/2020\/06\/Balla-Moussa-Keita.jpg","datePublished":"2021-02-05T22:18:29+00:00","dateModified":"2021-03-29T22:00:52+00:00","description":"Les derni\u00e8res news sur l\u2019h\u00f4tellerie, les voyagistes et les compagnies a\u00e9riennes. Exp\u00e9rience client, avis et reportages. Touristic Afrik est un site sp\u00e9cialis\u00e9 du Groupe Financial Afrik.","breadcrumb":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/#primaryimage","url":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-content\/uploads\/2020\/06\/Balla-Moussa-Keita.jpg","contentUrl":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-content\/uploads\/2020\/06\/Balla-Moussa-Keita.jpg","width":940,"height":1024,"caption":"Balla Moussa Keita. (Photo Vincent Fournier)."},{"@type":"BreadcrumbList","@id":"https:\/\/www.financialafrik.com\/touristicafrik\/2021\/02\/05\/au-souvenir-de-kinshasa-sur-un-air-de-rumba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.financialafrik.com\/touristicafrik\/"},{"@type":"ListItem","position":2,"name":"Au souvenir de Kinshasa sur un air de Rumba"}]},{"@type":"WebSite","@id":"https:\/\/www.financialafrik.com\/touristicafrik\/#website","url":"https:\/\/www.financialafrik.com\/touristicafrik\/","name":"Touristic Afrik","description":"L\u2019actualit\u00e9 touristique africaine","publisher":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.financialafrik.com\/touristicafrik\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.financialafrik.com\/touristicafrik\/#organization","name":"Touristic Afrik","url":"https:\/\/www.financialafrik.com\/touristicafrik\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.financialafrik.com\/touristicafrik\/#\/schema\/logo\/image\/","url":"https:\/\/touristicafrik.com\/wp-content\/uploads\/2022\/03\/blog-FA_Plan-de-travail-1.png","contentUrl":"https:\/\/touristicafrik.com\/wp-content\/uploads\/2022\/03\/blog-FA_Plan-de-travail-1.png","width":1115,"height":242,"caption":"Touristic Afrik"},"image":{"@id":"https:\/\/www.financialafrik.com\/touristicafrik\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FinancialAfrik\/","https:\/\/x.com\/Financialafrik","https:\/\/www.instagram.com\/financial_afrik\/","https:\/\/www.linkedin.com\/pub\/financial-afrik\/71\/727\/4bb","https:\/\/www.youtube.com\/channel\/UCSeoXcgLHLSVaKqMP7cQaJQ\/"]},{"@type":"Person","@id":"https:\/\/www.financialafrik.com\/touristicafrik\/#\/schema\/person\/ccf215c04eace169146fe681d585b837","name":"Balla Moussa Keita","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/4dcb5af52f0a864e870758e648ac35d7815718bac8b99244bd3943efaca1f896?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4dcb5af52f0a864e870758e648ac35d7815718bac8b99244bd3943efaca1f896?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4dcb5af52f0a864e870758e648ac35d7815718bac8b99244bd3943efaca1f896?s=96&d=mm&r=g","caption":"Balla Moussa Keita"},"description":"30 ans de voyage dans 37 des 54 pays africains. Les chroniques de Balla Moussa Keita offrent une image nette de l'Afrique en mouvement, \u00e0 travers ses paysages, l'ambiance de ses villes mais aussi les rapports sociaux entre tribus et ethnies. De nationalit\u00e9 ivoirienne, Balla Moussa Keita a travaill\u00e9 dans de nombreux m\u00e9dias panafricains.","url":"https:\/\/www.financialafrik.com\/touristicafrik\/author\/balla-moussa-keita\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-content\/uploads\/2020\/06\/Balla-Moussa-Keita.jpg","jetpack_shortlink":"https:\/\/wp.me\/pa7a93-7e","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/posts\/448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/comments?post=448"}],"version-history":[{"count":2,"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/posts\/448\/revisions"}],"predecessor-version":[{"id":450,"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/posts\/448\/revisions\/450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/media\/393"}],"wp:attachment":[{"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/media?parent=448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/categories?post=448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.financialafrik.com\/touristicafrik\/wp-json\/wp\/v2\/tags?post=448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}